{"id":9832,"date":"2022-03-18T13:12:28","date_gmt":"2022-03-18T12:12:28","guid":{"rendered":"https:\/\/www.bonals.com\/?page_id=9832"},"modified":"2025-03-12T16:57:56","modified_gmt":"2025-03-12T15:57:56","slug":"presse-rotative-m150s","status":"publish","type":"page","link":"https:\/\/www.bonals.com\/fr\/presse-rotative-m150s\/","title":{"rendered":"Presse rotative M150"},"content":{"rendered":"[vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1633602455878{margin-top: 0px !important;padding-top: 0px !important;background: #ffffff url(https:\/\/bonals.com\/wp-content\/uploads\/2021\/10\/M150-0010-1.jpg?id=5522) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00a0\u00bb][vc_column][vc_row_inner][vc_column_inner width=\u00a0\u00bb3\/4&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/4&Prime; css=\u00a0\u00bb.vc_custom_1631566282983{margin-top: 0px !important;margin-right: 0px !important;padding-top: 0px !important;padding-bottom: 160px !important;background-position: 0 0 !important;background-repeat: no-repeat !important;}\u00a0\u00bb][vc_single_image image=\u00a0\u00bb7567&Prime; alignment=\u00a0\u00bbright\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1634008305574{margin-right: 0px !important;padding-right: 0px !important;}\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1631593364861{margin-right: 40px !important;}\u00a0\u00bb][vc_row_inner css=\u00a0\u00bb.vc_custom_1631567196156{margin-top: 20px !important;}\u00a0\u00bb][vc_column_inner css=\u00a0\u00bb.vc_custom_1631567416688{margin-right: 50px !important;}\u00a0\u00bb][vc_column_text text_align=\u00a0\u00bbleft\u00a0\u00bb width=\u00a0\u00bb600px\u00a0\u00bb color=\u00a0\u00bb#163041&Prime; font_size=\u00a0\u00bb22px\u00a0\u00bb font_family=\u00a0\u00bbNunito\u00a0\u00bb font_weight=\u00a0\u00bb500&Prime; css=\u00a0\u00bb.vc_custom_1633602004524{padding-top: 30px !important;}\u00a0\u00bb]\n<h1>Presse rotative M150<\/h1>\n<h2>La M150 vous permettra de produire des tablettes mono ou multi-couche. Elle est utilis\u00e9e pour produire de grands volumes ou plus petites s\u00e9ries. Cette machine poss\u00e8de une r\u00e9putation \u00e9tablie de robustesse et de fiabilit\u00e9 pour un investissement r\u00e9duit.<\/h2>\n[\/vc_column_text][vc_empty_space][vc_column_text]Consid\u00e9r\u00e9e comme l&rsquo;une des meilleures presses pour la d\u00e9tergence du march\u00e9, install\u00e9e sur plus de 100 lignes de production, la M150 est une presse enti\u00e8rement automatis\u00e9e con\u00e7ue pour r\u00e9pondre aux besoins d&rsquo;une ligne de production \u00e0 vitesse moyenne de tablettes d\u00e9tergentes, mono ou multicouches, et pour tous types de formes.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1631593375869{padding-left: 40px !important;}\u00a0\u00bb][vc_row_inner][vc_column_inner][vc_empty_space height=\u00a0\u00bb100px\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb7503&Prime; img_size=\u00a0\u00bb100&Prime;]<h3 class=\"vcex-heading vcex-module wpex-text-2xl wpex-font-normal wpex-m-auto wpex-max-w-100 vcex-heading-plain wpex-block\"><span class=\"vcex-heading-inner wpex-inline-block wpex-clr\">Tablette<\/span><\/h3>[vc_column_text]Diam\u00e8tre jusqu&rsquo;\u00e0 54 mm<br \/>\nHauteur jusqu&rsquo;\u00e0 31 mm<br \/>\nTailles et formes sp\u00e9ciales sur demande[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb7505&Prime; img_size=\u00a0\u00bb100&Prime;]<h3 class=\"vcex-heading vcex-module wpex-text-2xl wpex-font-normal wpex-m-auto wpex-max-w-100 vcex-heading-plain wpex-block\"><span class=\"vcex-heading-inner wpex-inline-block wpex-clr\">Couches<\/span><\/h3>[vc_column_text]De 1 \u00e0 3 couches[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner]<h3 class=\"vcex-heading vcex-module wpex-text-2xl wpex-font-normal wpex-m-auto wpex-max-w-100 vcex-heading-plain wpex-block\"><span class=\"vcex-heading-inner wpex-inline-block wpex-clr\">Grande vitesse<\/span><\/h3>[vc_column_text]Jusqu&rsquo;\u00e0 900 tablettes\/min[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb content_placement=\u00a0\u00bbtop\u00a0\u00bb bg_style=\u00a0\u00bbstretch\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1631567835918{padding-top: 80px !important;padding-bottom: 20px !important;}\u00a0\u00bb visibility=\u00a0\u00bbhidden\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1630516472016{margin-right: 20px !important;}\u00a0\u00bb]<h2 class=\"vcex-heading vcex-module wpex-text-2xl wpex-font-normal wpex-m-auto wpex-max-w-100 vcex-heading-plain wpex-block vc_custom_1630517594485\" style=\"font-size:28px;font-weight:600;\"><span class=\"vcex-heading-inner wpex-inline-block wpex-clr\">P20 : \u00c0 propos<\/span><\/h2>[vc_column_text text_align=\u00a0\u00bbleft\u00a0\u00bb]Vous avez besoin d&rsquo;une solution de compactage pr\u00eate \u00e0 l&#8217;emploi ?<br \/>\nVous souhaitez limiter le co\u00fbt de votre investissement ?<br \/>\nVous cherchez une solution adapt\u00e9e aux environnements exigeants ?<\/p>\n<p>Con\u00e7ue pour les lots de moyenne importance, la presse P20 est l&rsquo;une des presses pour cubes ou tablettes de bouillon les plus compactes du march\u00e9 qui permet une production de haute qualit\u00e9 avec une efficacit\u00e9 maximale.<\/p>\n<p>Gr\u00e2ce \u00e0 sa technologie de poin\u00e7on unique et de compression adapt\u00e9e au bouillon, la presse P20 r\u00e9duit les d\u00e9chets de poudre &#8211; les poin\u00e7ons \u00e9tant nettoy\u00e9s apr\u00e8s \u00e9jection &#8211; et permet une connexion optimale \u00e0 toute machine d&#8217;emballage garantissant une manipulation fluide du produit. L&rsquo;acc\u00e8s complet \u00e0 la zone sup\u00e9rieure de la presse garantit un nettoyage et un entretien faciles.[\/vc_column_text]<div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:40px\"><\/div>[\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1630519252530{margin-left: 20px !important;}\u00a0\u00bb]<h2 class=\"vcex-heading vcex-module wpex-text-2xl wpex-font-normal wpex-m-auto wpex-max-w-100 vcex-heading-plain wpex-block vc_custom_1630517674407\" style=\"font-size:28px;font-weight:600;\"><span class=\"vcex-heading-inner wpex-inline-block wpex-clr\">Produits<\/span><\/h2>[vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][\/vc_column_inner][\/vc_row_inner]<h2 class=\"vcex-heading vcex-module wpex-text-2xl wpex-font-normal wpex-m-auto wpex-max-w-100 vcex-heading-plain wpex-block vc_custom_1630518226229\" style=\"font-size:28px;font-weight:600;\"><span class=\"vcex-heading-inner wpex-inline-block wpex-clr\">Rendement<\/span><\/h2>[vc_column_text]Jusqu&rsquo;\u00e0 <strong>800 cubes\/min*<\/strong><br \/>\nJusqu&rsquo;\u00e0 <strong>600 tablettes\/min*<\/strong><br \/>\n<em>*le rendement d\u00e9pend de la poudre et des conditions de fonctionnement<\/em>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bbnone\u00a0\u00bb full_width=\u00a0\u00bbstretch_row\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb bg_style=\u00a0\u00bbstretch\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1635079488486{margin-top: 100px !important;margin-bottom: 100px !important;padding-top: 60px !important;padding-bottom: 20px !important;background-color: #163041 !important;}\u00a0\u00bb visibility=\u00a0\u00bbhide-at-mm-breakpoint\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1630519265360{margin-top: -200px !important;margin-right: 20px !important;margin-bottom: -200px !important;}\u00a0\u00bb][vc_single_image image=\u00a0\u00bb11664&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1631593881840{padding-left: 40px !important;}\u00a0\u00bb]<h2 class=\"vcex-heading vcex-module wpex-text-2xl wpex-font-normal wpex-m-auto wpex-max-w-100 vcex-heading-plain wpex-block\" style=\"font-size:28px;font-weight:600;\"><span class=\"vcex-heading-inner wpex-inline-block wpex-clr\">Avantages<\/span><\/h2><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:30px\"><\/div><div style=\"color:#ffffff;line-height:28px;\" class=\"vcex-module vcex-bullets custom-icon\">\n<ul>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Co\u00fbts d&rsquo;investissement r\u00e9duits<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">R\u00e9gularit\u00e9 \u00e9lev\u00e9e du poids des comprim\u00e9s<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Duret\u00e9 optimale des tablettes<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Manipulation ais\u00e9e des tablettes<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">R\u00e9duction de la masse collante et de la perte de masse<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">R\u00e9glage et contr\u00f4le intuitifs de la production<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Op\u00e9rations faciles et maintenance facilit\u00e9e<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Taille compacte pour un encombrement minimal<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Int\u00e9gration efficace \u00e0 la ligne d&#8217;emballage<\/div><\/div><\/li>\n<\/ul>\n<\/div>[\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bbnone\u00a0\u00bb full_width=\u00a0\u00bbstretch_row\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb bg_style=\u00a0\u00bbstretch\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1635079496029{margin-top: 100px !important;margin-bottom: 100px !important;padding-top: 60px !important;padding-bottom: 20px !important;background-color: #163041 !important;}\u00a0\u00bb visibility=\u00a0\u00bbshow-at-mm-breakpoint\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1630519265360{margin-top: -200px !important;margin-right: 20px !important;margin-bottom: -200px !important;}\u00a0\u00bb][vc_single_image image=\u00a0\u00bb11664&Prime;][vc_empty_space height=\u00a0\u00bb250px\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1631593881840{padding-left: 40px !important;}\u00a0\u00bb]<h2 class=\"vcex-heading vcex-module wpex-text-2xl wpex-font-normal wpex-m-auto wpex-max-w-100 vcex-heading-plain wpex-block\" style=\"font-size:28px;font-weight:600;\"><span class=\"vcex-heading-inner wpex-inline-block wpex-clr\">Avantages<\/span><\/h2><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:30px\"><\/div><div style=\"color:#ffffff;line-height:28px;\" class=\"vcex-module vcex-bullets custom-icon\">\n<ul>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Co\u00fbts d&rsquo;investissement r\u00e9duits<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">R\u00e9gularit\u00e9 \u00e9lev\u00e9e du poids des comprim\u00e9s<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Duret\u00e9 optimale des tablettes<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Manipulation ais\u00e9e des tablettes<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">R\u00e9duction de la masse collante et de la perte de masse<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">R\u00e9glage et contr\u00f4le intuitifs de la production<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Op\u00e9rations faciles et maintenance facilit\u00e9e<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Taille compacte pour un encombrement minimal<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#ffffff;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Int\u00e9gration efficace \u00e0 la ligne d&#8217;emballage<\/div><\/div><\/li>\n<\/ul>\n<\/div>[\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1630521307413{margin-top: 70px !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/3&Prime;]<div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:30px\"><\/div><h2 class=\"vcex-heading vcex-module wpex-text-2xl wpex-font-normal wpex-m-auto wpex-max-w-100 vcex-heading-plain wpex-block\" style=\"font-size:28px;font-weight:600;\"><span class=\"vcex-heading-inner wpex-inline-block wpex-clr\">Fonctionnalit\u00e9s<\/span><\/h2><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:30px\"><\/div><div style=\"color:#163041;line-height:28px;\" class=\"vcex-module vcex-bullets custom-icon\">\n<ul>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#163041;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Technologie double poin\u00e7ons<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#163041;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Syst\u00e8me d&rsquo;alimentation optimum<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#163041;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Syst\u00e8me d&rsquo;\u00e9jection central unique<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#163041;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Syst\u00e8me de nettoyage automatique des poin\u00e7ons<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#163041;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Interface \u00e0 \u00e9cran tactile 19\u00a0\u00bb, SmartPress (enoption)<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#163041;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Carenage sup\u00e9rieur insonoris\u00e9<\/div><\/div><\/li>\n<li><div class=\"vcex-bullets-ci-wrap wpex-inline-flex\"><span class=\"vcex-icon-wrap wpex-mr-5\"><span class=\"vcex-icon fas fa-angle-right\" aria-hidden=\"true\" style=\"color:#163041;\"><\/span><\/span><div class=\"vcex-content wpex-flex-grow\">Zone d&rsquo;entra\u00eenement int\u00e9gr\u00e9e et sans vibration<\/div><\/div><\/li>\n<\/ul>\n<\/div>[\/vc_column][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_video link=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=WjYSLqlouqA\u00a0\u00bb el_width=\u00a0\u00bb90&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1630520856920{background-color: #068ca9 !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/3&Prime; css=\u00a0\u00bb.vc_custom_1630520900002{padding-top: 30px !important;}\u00a0\u00bb][vc_single_image image=\u00a0\u00bb7339&Prime; alignment=\u00a0\u00bbcenter\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1630521627864{padding-top: 30px !important;}\u00a0\u00bb][vc_column_text color=\u00a0\u00bb#ffffff\u00a0\u00bb font_size=\u00a0\u00bb20&Prime; font_weight=\u00a0\u00bb500&Prime; text_align=\u00a0\u00bbcenter\u00a0\u00bb]Le saviez-vous?[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_column_text color=\u00a0\u00bb#ffffff\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1645526767426{padding-top: 50px !important;padding-bottom: 30px !important;}\u00a0\u00bb]<strong>Simplifiez-vous la vie |<\/strong> Notre IHM avanc\u00e9e offre un syst\u00e8me d&rsquo;exploitation simple et intuitif pour faciliter les op\u00e9rations, minimiser les risques d&rsquo;erreurs humaines tout en optimisant les op\u00e9rations de maintenance et la formation des op\u00e9rateurs. Son \u00e9cran tactile de 19\u00a0\u00bb donne un acc\u00e8s direct \u00e0ux graphiques lors du process. Le tableau de bord, gr\u00e2ce \u00e0 ses pictogrammes, vous permet de configurer les param\u00e8tres de production, \u00e0 ex\u00e9cuter et \u00e0 surveiller les op\u00e9rations.<\/p>\n<p><strong>Options compl\u00e9mentaires<\/strong> | SmartPress Maintenance (module d\u2019entretien) &#8211; qui fournit aux op\u00e9rateurs des tutoriels en 3D, de la documentation sur les produits, le SmartPress Reporting (module de rapport) qui calcule et analyse le rendement global de votre \u00e9quipement (TRG) en temps r\u00e9el pour am\u00e9liorer l&rsquo;efficacit\u00e9 de votre production. Le module Surveillance SmartPress vous permet d&rsquo;enregistrer, d&rsquo;analyser et de prot\u00e9ger l&rsquo;utilisation de votre presse.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:80px\"><\/div><div class=\"vcex-module wpex-carousel wpex-carousel-images wpex-clr owl-carousel wpex-carousel-items-center\" data-wpex-carousel=\"{&quot;nav&quot;:false,&quot;dots&quot;:false,&quot;autoplay&quot;:true,&quot;loop&quot;:true,&quot;center&quot;:false,&quot;smartSpeed&quot;:250,&quot;items&quot;:3,&quot;slideBy&quot;:1,&quot;autoplayTimeout&quot;:5000,&quot;margin&quot;:15,&quot;itemsTablet&quot;:3,&quot;itemsMobileLandscape&quot;:2,&quot;itemsMobilePortrait&quot;:1,&quot;autoWidth&quot;:false,&quot;autoHeight&quot;:false}\"><div class=\"wpex-carousel-slide\"><figure class=\"wpex-carousel-entry-media entry-media\"><img decoding=\"async\" data-no-lazy=\"1\" class=\"wpex-align-middle skip-lazy\" src=\"https:\/\/www.bonals.com\/wp-content\/uploads\/2022\/12\/DSC_0922-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" \/><\/figure><\/div><div class=\"wpex-carousel-slide\"><figure class=\"wpex-carousel-entry-media entry-media\"><img decoding=\"async\" data-no-lazy=\"1\" class=\"wpex-align-middle skip-lazy\" src=\"https:\/\/www.bonals.com\/wp-content\/uploads\/2022\/12\/DSC_0924-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" \/><\/figure><\/div><div class=\"wpex-carousel-slide\"><figure class=\"wpex-carousel-entry-media entry-media\"><img decoding=\"async\" data-no-lazy=\"1\" class=\"wpex-align-middle skip-lazy\" src=\"https:\/\/www.bonals.com\/wp-content\/uploads\/2022\/12\/DSC_0926-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" \/><\/figure><\/div><\/div><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:60px\"><\/div>[\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb el_class=\u00a0\u00bbvisible_forced\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_icon icon_fontawesome=\u00a0\u00bbfas fa-file-download\u00a0\u00bb size=\u00a0\u00bbxl\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb el_class=\u00a0\u00bbicop20&Prime;][\/vc_column][vc_column width=\u00a0\u00bb2\/3&Prime;][vc_toggle title=\u00a0\u00bbT\u00e9l\u00e9charger la fiche technique M150&Prime; style=\u00a0\u00bbsimple\u00a0\u00bb color=\u00a0\u00bbblue\u00a0\u00bb custom_font_container=\u00a0\u00bbtag:h2|text_align:left|color:%23068ca9&Prime; custom_use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb use_custom_heading=\u00a0\u00bbtrue\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1638296519640{background-color: #ffffff !important;}\u00a0\u00bb el_id=\u00a0\u00bbp20datasheet\u00a0\u00bb]<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f7826-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/9832#wpcf7-f7826-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"7826\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7826-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div>\n<p class=\"bleu\" style=\"padding-top: 20px; padding-bottom: 20px\">Please fill in the form below to download the M150 datasheet PDF<\/p>\n<\/div>\n<div id=\"cf7md-form\" class=\"cf7md-form\">\n\t\t\t<div class=\"mdc-layout-grid\">\n\t\t\t\t<div class=\"mdc-layout-grid__inner\">\n\t\t\t\t\t\t\t\t\t\t\n<div id=\"responsive-form\" class=\"clearfix\">\n<div class=\"form-row formpied column\">\n<div class=\"formpied column\">\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12\">\n\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-first-name\"><input type=\"text\" name=\"your-first-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">First name<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n<\/div>\n<div class=\"form-row formpied  column\">\n<div class=\"formpied column\">\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12\">\n\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-last-name\"><input type=\"text\" name=\"your-last-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Last name<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n<\/div>\n<div class=\"form-row formpied \">\n<div class=\"formpied column\">\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12\">\n\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Email address<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n<\/div>\n<div class=\"formpied column\">\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12\">\n\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input type=\"tel\" name=\"your-phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Phone<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"form-row formpied\">\n<div class=\"formpied column\">\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12\">\n\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-company\"><input type=\"text\" name=\"your-company\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Company<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n<\/div>\n<div class=\"form-row formpied \">\n<div class=\"formpied column\"><span class=\"wpcf7-form-control-wrap\" data-name=\"zone\"><select name=\"zone\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"Your geographic area:*\">Your geographic area:*<\/option><option value=\"Africa &amp; Middle East\">Africa &amp; Middle East<\/option><option value=\"America (north - south - central)\">America (north - south - central)<\/option><option value=\"Asia\">Asia<\/option><option value=\"Europe\">Europe<\/option><option value=\"Oceania\">Oceania<\/option><\/select><\/span><\/div>\n<\/div>\n<div class=\"column-full\" style=\"text-align: center\">\t\t<div class=\"cf7md-item cf7md-submit mdc-layout-grid__cell mdc-layout-grid__cell--span-12\" data-button-style=\"raised\">\n\t\t\t<input type=\"submit\" value=\"Send\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/>\t\t\t<svg class=\"cf7md-spinner\" width=\"25px\" height=\"25px\" viewBox=\"0 0 66 66\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle class=\"cf7md-spinner-path\" fill=\"none\" stroke-width=\"6\" stroke-linecap=\"round\" cx=\"33\" cy=\"33\" r=\"30\"><\/circle>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t\n      <\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n<div class=\"inv-recaptcha-holder\"><\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>[\/vc_toggle][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1633418059658{background-color: #f2f2f2 !important;}\u00a0\u00bb][vc_column]<div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:60px\"><\/div><h2 class=\"vcex-heading vcex-module wpex-text-2xl wpex-font-normal wpex-m-auto wpex-max-w-100 vcex-heading-plain wpex-block wpex-text-center\" style=\"font-size:28px;font-weight:600;\"><span class=\"vcex-heading-inner wpex-inline-block wpex-clr\">Autres solutions<\/span><\/h2><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:40px\"><\/div>[vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb7511&Prime; add_caption=\u00a0\u00bbyes\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb img_caption=\u00a0\u00bbG200 Rotary press\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/www.bonals.com\/fr\/presse-rotative-g200\/\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb7365&Prime; add_caption=\u00a0\u00bbyes\u00a0\u00bb alignment=\u00a0\u00bbright\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb img_caption=\u00a0\u00bbServices\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/www.bonals.com\/fr\/prestations-de-service\/\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=\u00a0\u00bb.vc_custom_1631568024881{margin-top: 70px !important;}\u00a0\u00bb visibility=\u00a0\u00bbhidden\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/3&Prime;]<h2 class=\"vcex-heading vcex-module wpex-text-2xl wpex-font-normal wpex-m-auto wpex-max-w-100 vcex-heading-plain wpex-block\" style=\"font-size:28px;font-weight:600;\"><span class=\"vcex-heading-inner wpex-inline-block wpex-clr\">Donn\u00e9es techniques<\/span><\/h2><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:30px\"><\/div>[vc_row_inner css=\u00a0\u00bb.vc_custom_1630522602881{margin-bottom: 20px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb2\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522510356{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]<strong>Nombre de sortie<\/strong>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522516955{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]1[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=\u00a0\u00bb.vc_custom_1630522612864{margin-bottom: 20px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb2\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522522490{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]<strong>Nombre de stations<\/strong>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522527996{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]16[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=\u00a0\u00bb.vc_custom_1630522612864{margin-bottom: 20px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb2\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522522490{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]<strong>Diam\u00e8tre<br \/>\n<\/strong>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522527996{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]300mm[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=\u00a0\u00bb.vc_custom_1630522612864{margin-bottom: 20px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb2\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522522490{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]<strong>Vitesse maximale de la tourelle<\/strong>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522527996{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]25 tr\/min[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=\u00a0\u00bb.vc_custom_1630522612864{margin-bottom: 20px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb2\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522522490{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]<strong>Charge de compression<\/strong>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522527996{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]Jusqu&rsquo;\u00e0 20kN[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=\u00a0\u00bb.vc_custom_1630522612864{margin-bottom: 20px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb2\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522522490{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]<strong>Consommation \u00e9lectrique maximale <\/strong>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522527996{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]10kVA[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=\u00a0\u00bb.vc_custom_1630522612864{margin-bottom: 20px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb2\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522522490{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]<strong>Poids<\/strong>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/3&Prime; css=\u00a0\u00bb.vc_custom_1630522527996{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text]1.200kg[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=\u00a0\u00bb2\/3&Prime;]<div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:30px\"><\/div>[vc_single_image image=\u00a0\u00bb7341&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u00a0\u00bb60&Prime;][vc_column_text text_align=\u00a0\u00bbcenter\u00a0\u00bb]\n<h2>Nous contacter<\/h2>\n[\/vc_column_text][vc_empty_space height=\u00a0\u00bb40&Prime;]<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f5256-o2\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/9832#wpcf7-f5256-o2\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"5256\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.6.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5256-o2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div>\n<p>Contact us today to learn how Bonals Technologies can support your business. Fill out the form below and our experts will advise you on the best solution for your project.<\/p>\n<\/div>\n<div id=\"cf7md-form\" class=\"cf7md-form cf7md-spacing--tight\">\n\t\t\t<div class=\"mdc-layout-grid\">\n\t\t\t\t<div class=\"mdc-layout-grid__inner\">\n\t\t\t\t\t\t\t\t\t\t\n<div id=\"responsive-form\" class=\"clearfix\">\n<div class=\"form-row formpied\">\n<div class=\"form-row formpied  column-half\">\n<div class=\"formpied column-half\">\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12\">\n\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-first-name\"><input type=\"text\" name=\"your-first-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">First name<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n<div class=\"formpied column-half\">\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12\">\n\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-last-name\"><input type=\"text\" name=\"your-last-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Last name<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n<div class=\"formpied column-half\">\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12\">\n\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-company\"><input type=\"text\" name=\"your-company\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Company<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n<div class=\"formpied column-half\"><span class=\"wpcf7-form-control-wrap\" data-name=\"zone\"><select name=\"zone\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"Your geographic area:*\">Your geographic area:*<\/option><option value=\"Africa &amp; Middle East\">Africa &amp; Middle East<\/option><option value=\"America (north - south - central)\">America (north - south - central)<\/option><option value=\"Asia\">Asia<\/option><option value=\"Europe\">Europe<\/option><option value=\"Oceania\">Oceania<\/option><\/select><\/span><\/div>\n<div class=\"formpied column-half\">\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12\">\n\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Email address<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n<div class=\"formpied column-half\">\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-12\">\n\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input type=\"tel\" name=\"your-phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span>\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Phone<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n<div class=\"formpied  column-full\">\n        \t\t<div class=\"cf7md-item cf7md-select mdc-layout-grid__cell mdc-layout-grid__cell--span-12\">\n\t\t\t<br \/>\n          <span class=\"wpcf7-form-control-wrap\" data-name=\"menu-397\"><select name=\"menu-397\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"Talk to a member of our Sales team\">Talk to a member of our Sales team<\/option><option value=\"Product and account support\">Product and account support<\/option><\/select><\/span><br \/>\n        \t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-select-html\">\n\t\t\t\t<div class=\"mdc-select  mdc-select--outlined\">\n\t\t\t\t\t\t\n\t\t\t\t\t<i class=\"mdc-select__dropdown-icon\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Contact type<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n      <\/div>\n<div class=\"column-full\" style=\"text-align: right\">\t\t<div class=\"cf7md-item cf7md-submit mdc-layout-grid__cell mdc-layout-grid__cell--span-12\" data-button-style=\"raised\">\n\t\t\t<input type=\"submit\" value=\"Send\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/>\t\t\t<svg class=\"cf7md-spinner\" width=\"25px\" height=\"25px\" viewBox=\"0 0 66 66\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle class=\"cf7md-spinner-path\" fill=\"none\" stroke-width=\"6\" stroke-linecap=\"round\" cx=\"33\" cy=\"33\" r=\"30\"><\/circle>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t\n      <\/div>\n<\/div>\n<div class=\"form-row formpied column-half\">\n<div class=\"column-full text-area-expended\">\n\t\t<div class=\"cf7md-item cf7md-textarea mdc-layout-grid__cell mdc-layout-grid__cell--span-12 cf7md-textarea-autosize\">\n\t\t\t<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><\/textarea><\/span>\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--textarea\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Message<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n<div class=\"inv-recaptcha-holder\"><\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1633602455878{margin-top: 0px !important;padding-top: 0px !important;background: #ffffff url(https:\/\/bonals.com\/wp-content\/uploads\/2021\/10\/M150-0010-1.jpg?id=5522) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00a0\u00bb][vc_column][vc_row_inner][vc_column_inner width=\u00a0\u00bb3\/4&Prime;][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/4&Prime; css=\u00a0\u00bb.vc_custom_1631566282983{margin-top: 0px !important;margin-right: 0px !important;padding-top: 0px !important;padding-bottom: 160px !important;background-position: 0 0 !important;background-repeat: no-repeat !important;}\u00a0\u00bb][vc_single_image image=\u00a0\u00bb7567&Prime; alignment=\u00a0\u00bbright\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1634008305574{margin-right: 0px !important;padding-right: 0px !important;}\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime; css=\u00a0\u00bb.vc_custom_1631593364861{margin-right: 40px !important;}\u00a0\u00bb][vc_row_inner css=\u00a0\u00bb.vc_custom_1631567196156{margin-top: 20px !important;}\u00a0\u00bb][vc_column_inner css=\u00a0\u00bb.vc_custom_1631567416688{margin-right: 50px !important;}\u00a0\u00bb][vc_column_text text_align=\u00a0\u00bbleft\u00a0\u00bb width=\u00a0\u00bb600px\u00a0\u00bb color=\u00a0\u00bb#163041&Prime; font_size=\u00a0\u00bb22px\u00a0\u00bb font_family=\u00a0\u00bbNunito\u00a0\u00bb font_weight=\u00a0\u00bb500&Prime;&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-9832","page","type-page","status-publish","hentry","entry","no-media"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.bonals.com\/fr\/wp-json\/wp\/v2\/pages\/9832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonals.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bonals.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bonals.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bonals.com\/fr\/wp-json\/wp\/v2\/comments?post=9832"}],"version-history":[{"count":21,"href":"https:\/\/www.bonals.com\/fr\/wp-json\/wp\/v2\/pages\/9832\/revisions"}],"predecessor-version":[{"id":12783,"href":"https:\/\/www.bonals.com\/fr\/wp-json\/wp\/v2\/pages\/9832\/revisions\/12783"}],"wp:attachment":[{"href":"https:\/\/www.bonals.com\/fr\/wp-json\/wp\/v2\/media?parent=9832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}